{"id":2750,"date":"2022-02-24T11:38:14","date_gmt":"2022-02-24T10:38:14","guid":{"rendered":"https:\/\/degrados.es\/producto\/absinth-classic-55-70cl\/"},"modified":"2023-12-19T13:02:23","modified_gmt":"2023-12-19T12:02:23","slug":"absinth-classic-55-70cl","status":"publish","type":"product","link":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/","title":{"rendered":"Absinth Classic 55 (70cl)"},"content":{"rendered":"<p>Absinthe Classic 55\u00ba ist ein spektakul\u00e4rer Absinthe mit intensiv roter Farbe, der nach traditioneller Art und Weise aus folgenden Komponenten hergestellt wird:<\/p>\n<p>Der Wermut (Artemisia absinthium) geh\u00f6rt zur Familie der Korbbl\u00fctler. Diese auch als &#8220;heiliges Gras&#8221; bezeichnete Pflanze ist in den gem\u00e4\u00dfigten Regionen Europas, Asiens und Nordafrikas heimisch.<\/p>\n<p>Eine weitere der Pflanzen, aus denen der klassische Serpis-Absinth besteht, ist der Fenchel, der an der Mittelmeerk\u00fcste oft wild w\u00e4chst. Es ist ein hocharomatisches, mehrj\u00e4hriges Kraut, das f\u00fcr kulinarische Zwecke angebaut wird.<\/p>\n<p>Anis schlie\u00dflich ist eine Pflanze aus S\u00fcdwestasien und dem \u00f6stlichen Mittelmeerraum. Durch Destillation der Samen wird ein \u00e4therisches \u00d6l freigesetzt, das zur Behandlung von Verdauungsst\u00f6rungen verwendet wird.<\/p>\n<p>Der <strong>nach der alten Formel<\/strong> hergestellte <strong>Absinthe Classic<\/strong><strong>55\u00ba<\/strong><strong> gilt <\/strong>aufgrund seines hohen Thujongehalts<strong> als einer der komplexesten auf dem internationalen Markt <\/strong>. Thujon ist ein \u00e4therisches \u00d6l, das in Wermut und vielen anderen Pflanzen vorkommt und antibakterielle, emmenagogische und krampfl\u00f6sende Eigenschaften hat. Es hat jedoch aufgrund seiner halluzinogenen Nebenwirkungen eine Kontroverse ausgel\u00f6st.<\/p>\n<p><strong>Absinthe Classic<\/strong><strong>55\u00ba<\/strong> hat einen intensiven und komplexen Geschmack und eignet sich zum Trinken pur, mit Wasser oder Slush. Die angemessenste Art, ihn zu genie\u00dfen, ist jedoch immer noch der traditionelle Ritus: ein durchl\u00f6cherter L\u00f6ffel mit einem St\u00fcck Zucker darauf, der mit dem Absinth \u00fcbergossen wird und den Klumpen tr\u00e4nkt, dann wird er angez\u00fcndet und kaltes Wasser nach Geschmack \u00fcber den L\u00f6ffel gegossen, um den Inhalt zu reduzieren.<\/p>\n<p>Eines der Getr\u00e4nke, das niemanden gleichg\u00fcltig l\u00e4sst. Als treue Inspiration f\u00fcr die gro\u00dfen K\u00fcnstler des 19. Jahrhunderts und umstritten wegen seiner Wirkung, l\u00e4sst Absinth Classic 55\u00ba keinen Termin aus.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"references\">Der nach der alten Formel hergestellte Absinthe Classic 55\u00ba enth\u00e4lt einen hohen Thujongehalt. Er hat einen intensiven und komplexen Geschmack und kann pur, mit Wasser oder in Form von Slushies getrunken werden, wobei der traditionelle Ritus mit einem gelochten L\u00f6ffel und Zucker wohl die authentischste Art ist, ihn zu genie\u00dfen.<\/div>\n","protected":false},"featured_media":3843,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[540,530],"product_tag":[585,587,588,531],"class_list":["post-2750","product","type-product","status-publish","has-post-thumbnail","product_cat-cazalla-de","product_cat-spirituosen","product_tag-absinth","product_tag-absinth-klassiker","product_tag-absinthe-classic-55-de","product_tag-spirituosen","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store<\/title>\n<meta name=\"description\" content=\"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Spirituosengesch\u00e4ft\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T12:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/degrados.es\/wp-content\/uploads\/2022\/02\/absenta-licor-55-70cl.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"430\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"20,85&euro; IVA Incluido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/\",\"url\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/\",\"name\":\"Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Absenta-Classic-55o.webp\",\"datePublished\":\"2022-02-24T10:38:14+00:00\",\"dateModified\":\"2023-12-19T12:02:23+00:00\",\"description\":\"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Absenta-Classic-55o.webp\",\"contentUrl\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Absenta-Classic-55o.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Absenta Classic 55 (70cl)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/producto\\\/absinth-classic-55-70cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degrados.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/degrados.es\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Absinth Classic 55 (70cl)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/degrados.es\\\/de\\\/\",\"name\":\"DeGrados - Licorer\u00eda Online\",\"description\":\"Spirituosen online kaufen\",\"publisher\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#organization\"},\"alternateName\":\"Licorer\u00eda online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degrados.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#organization\",\"name\":\"DeGrados\",\"url\":\"https:\\\/\\\/degrados.es\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-degrados.png\",\"contentUrl\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-degrados.png\",\"width\":350,\"height\":86,\"caption\":\"DeGrados\"},\"image\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"20.85\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"D1G55\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store","description":"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/","og_locale":"de_DE","og_type":"article","og_title":"Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store","og_description":"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados","og_url":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/","og_site_name":"Online Spirituosengesch\u00e4ft","article_modified_time":"2023-12-19T12:02:23+00:00","og_image":[{"width":430,"height":430,"url":"https:\/\/degrados.es\/wp-content\/uploads\/2022\/02\/absenta-licor-55-70cl.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"20,85&euro; IVA Incluido","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/","url":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/","name":"Absinth kaufen - Absinth Lik\u00f6r - Degrados Online Liquor Store","isPartOf":{"@id":"https:\/\/degrados.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/#primaryimage"},"image":{"@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/#primaryimage"},"thumbnailUrl":"https:\/\/degrados.es\/wp-content\/uploads\/2022\/02\/Absenta-Classic-55o.webp","datePublished":"2022-02-24T10:38:14+00:00","dateModified":"2023-12-19T12:02:23+00:00","description":"Entdecken Sie den explosivsten Absinthe-Lik\u00f6r. Kaufen Sie einen exklusiven Absinth-Lik\u00f6r mit einem intensiven und komplexen Geschmack bei Licorer\u00eda Online : Degrados","breadcrumb":{"@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/#primaryimage","url":"https:\/\/degrados.es\/wp-content\/uploads\/2022\/02\/Absenta-Classic-55o.webp","contentUrl":"https:\/\/degrados.es\/wp-content\/uploads\/2022\/02\/Absenta-Classic-55o.webp","width":1000,"height":1000,"caption":"Absenta Classic 55 (70cl)"},{"@type":"BreadcrumbList","@id":"https:\/\/degrados.es\/de\/producto\/absinth-classic-55-70cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degrados.es\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/degrados.es\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Absinth Classic 55 (70cl)"}]},{"@type":"WebSite","@id":"https:\/\/degrados.es\/de\/#website","url":"https:\/\/degrados.es\/de\/","name":"DeGrados - Licorer\u00eda Online","description":"Spirituosen online kaufen","publisher":{"@id":"https:\/\/degrados.es\/de\/#organization"},"alternateName":"Licorer\u00eda online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degrados.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/degrados.es\/de\/#organization","name":"DeGrados","url":"https:\/\/degrados.es\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/degrados.es\/de\/#\/schema\/logo\/image\/","url":"https:\/\/degrados.es\/wp-content\/uploads\/2021\/02\/Logo-degrados.png","contentUrl":"https:\/\/degrados.es\/wp-content\/uploads\/2021\/02\/Logo-degrados.png","width":350,"height":86,"caption":"DeGrados"},"image":{"@id":"https:\/\/degrados.es\/de\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"20.85","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"D1G55","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/product\/2750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/comments?post=2750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/media\/3843"}],"wp:attachment":[{"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/media?parent=2750"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/product_brand?post=2750"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/product_cat?post=2750"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/degrados.es\/de\/wp-json\/wp\/v2\/product_tag?post=2750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}