{"id":411,"count":1,"description":"","link":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/","name":"sweet wine","slug":"sweet-wine","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online<\/title>\n<meta name=\"description\" content=\"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degrados.es\/en\/tag\/sweet-wine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online\" \/>\n<meta property=\"og:description\" content=\"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degrados.es\/en\/tag\/sweet-wine\/\" \/>\n<meta property=\"og:site_name\" content=\"Online Liquor Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/degrados.es\\\/en\\\/tag\\\/sweet-wine\\\/\",\"url\":\"https:\\\/\\\/degrados.es\\\/en\\\/tag\\\/sweet-wine\\\/\",\"name\":\"sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/#website\"},\"description\":\"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/en\\\/tag\\\/sweet-wine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degrados.es\\\/en\\\/tag\\\/sweet-wine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degrados.es\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sweet wine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degrados.es\\\/#website\",\"url\":\"https:\\\/\\\/degrados.es\\\/\",\"name\":\"Degrados\",\"description\":\"Buy liquors online\",\"publisher\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/#organization\"},\"alternateName\":\"Licorer\u00eda online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degrados.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degrados.es\\\/#organization\",\"name\":\"DeGrados\",\"url\":\"https:\\\/\\\/degrados.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/degrados.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-degrados.png\",\"contentUrl\":\"https:\\\/\\\/degrados.es\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo-degrados.png\",\"width\":350,\"height\":86,\"caption\":\"DeGrados\"},\"image\":{\"@id\":\"https:\\\/\\\/degrados.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online","description":"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/","og_locale":"en_US","og_type":"article","og_title":"sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online","og_description":"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.","og_url":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/","og_site_name":"Online Liquor Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/","url":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/","name":"sweet wine: Descubre m\u00e1s licores en Licorer\u00eda online","isPartOf":{"@id":"https:\/\/degrados.es\/#website"},"description":"Descubre m\u00e1s acerca de sweet wine en tu licorer\u00eda online con una selecci\u00f3n especial de licores \u00fanicos, vinos y bebidas para aperitivos.","breadcrumb":{"@id":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/degrados.es\/en\/tag\/sweet-wine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degrados.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"sweet wine"}]},{"@type":"WebSite","@id":"https:\/\/degrados.es\/#website","url":"https:\/\/degrados.es\/","name":"Degrados","description":"Buy liquors online","publisher":{"@id":"https:\/\/degrados.es\/#organization"},"alternateName":"Licorer\u00eda online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degrados.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/degrados.es\/#organization","name":"DeGrados","url":"https:\/\/degrados.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/degrados.es\/#\/schema\/logo\/image\/","url":"https:\/\/degrados.es\/wp-content\/uploads\/2021\/02\/Logo-degrados.png","contentUrl":"https:\/\/degrados.es\/wp-content\/uploads\/2021\/02\/Logo-degrados.png","width":350,"height":86,"caption":"DeGrados"},"image":{"@id":"https:\/\/degrados.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/degrados.es\/en\/wp-json\/wp\/v2\/tags\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/degrados.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/degrados.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/degrados.es\/en\/wp-json\/wp\/v2\/posts?tags=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}